{"id":3190,"date":"2020-04-15T12:46:49","date_gmt":"2020-04-15T10:46:49","guid":{"rendered":"https:\/\/rentasunnyplace.com\/corona-virus-vacation\/"},"modified":"2024-12-09T17:55:56","modified_gmt":"2024-12-09T16:55:56","slug":"cambio-registro","status":"publish","type":"post","link":"https:\/\/rentasunnyplace.com\/es\/cambio-registro\/","title":{"rendered":"CAMBIO EN EL REGISTRO DE HU\u00c9SPEDES EN ESPA\u00d1A"},"content":{"rendered":"\n<p><strong>CAMBIO EN EL REGISTRO DE HU\u00c9SPEDES EN ESPA\u00d1A<\/strong><\/p>\n\n\n\n<p>Diciembre 2024: <br>De acuerdo con el Real Decreto 933\/2021 del 26 de octubre, emitido por el gobierno espa\u00f1ol, y el <strong>nuevo sistema de registro<\/strong> que lo acompa\u00f1a, estamos obligados a solicitar <strong>informaci\u00f3n adicional<\/strong> a nuestros hu\u00e9spedes.<\/p>\n\n\n\n<p>A diferencia de otros proveedores, no pedimos esta informaci\u00f3n el d\u00eda de llegada, sino en el momento de la reserva. Esto permite a nuestros hu\u00e9spedes disfrutar de sus vacaciones desde el momento de su llegada sin preocuparse por formalidades.<\/p>\n\n\n\n<p>Hemos preparado un <strong>formulario f\u00e1cil de usar <\/strong>que puede ser compartido con nosotros a trav\u00e9s de una <strong>conexi\u00f3n segura<\/strong>. Adem\u00e1s, las copias necesarias de<strong> los documentos de identidad<\/strong> (para personas de 14 a\u00f1os o m\u00e1s) pueden cargarse de forma segura a trav\u00e9s de esta conexi\u00f3n. Una vez que haya reservado una propiedad, compartiremos con usted los detalles necesarios.<\/p>\n\n\n\n<p>De esta manera, Rentasunnyplace se asegura de que el impacto de la nueva normativa sea lo m\u00e1s limitado posible para nuestros hu\u00e9spedes.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><strong>CORONAVIRUS &amp; VACACIONES<\/strong><\/p>\n\n\n<p>15-01-2023: Y tambi\u00e9n este a\u00f1o continuaremos con nuestra opci\u00f3n de cancelaci\u00f3n gratuita con respecto a Corona. Eso significa: todos los pagos ser\u00e1n devueltos si no es posible viajar al alojamiento (per\u00edodo reservado) debido a las medidas gubernamentales de corona.<\/p>\n<p>01-11-2021: Una vez m\u00e1s tuvimos una temporada maravillosa con casi todas las villas continuamente ocupadas con hu\u00e9spedes muy satisfechos.<br \/>Continuaremos con nuestra opci\u00f3n de cancelaci\u00f3n gratuita, siempre que exista incertidumbre sobre el Virus Corona. Eso significa: todos los pagos devueltos si no es posible viajar al alojamiento (per\u00edodo reservado) debido a las medidas del gobierno de la corona.<\/p>\n<p>28-03-21: El a\u00f1o que viene tambi\u00e9n ofreceremos a nuestros hu\u00e9spedes la opci\u00f3n de cancelaci\u00f3n gratuita (todos los pagos devueltos) si debido a las medidas del gobierno de la corona, el c\u00f3digo del consejo de viaje para el alojamiento (per\u00edodo reservado) es naranja o rojo.<\/p>\n<p>05-09-20: A pesar de algunas restricciones, casi todas las villas de Rentasunnyplace se volvieron a reservar este verano. Aquellos que no pudieron venir debido al virus han recibido sus pagos (iniciales) al 100%. \u00a1As\u00ed es c\u00f3mo lo hacemos!<br \/>Los invitados que vinieron, experimentaron pocos obst\u00e1culos por las circunstancias y disfrutaron a\u00fan m\u00e1s de la tranquilidad de las villas.<\/p>\n<p>14-06-2020: Rentasunnyplace entiende que el coronavirus genera mucha incertidumbre.<\/p>\n<p>Para aquellos que ya est\u00e1n pensando en sus vacaciones, hemos tomado, en consulta con los propietarios, los siguientes pasos:<\/p>\n<ol>\n<li><strong>Cancelaci\u00f3n gratuita<\/strong> <strong>para reservas actuales.<\/strong><\/li>\n<\/ol>\n<p>Rentasunnyplace ofrece a todos sus hu\u00e9spedes que desean cancelar debido al coronavirus la oportunidad de hacerlo de forma gratuita. En cualquier caso, esto es posible hasta un mes antes de la llegada. En ese momento volveremos a evaluar la situaci\u00f3n juntos.<\/p>\n<ol start=\"2\">\n<li><strong>Nuevas reservas sin fianza.<\/strong><\/li>\n<\/ol>\n<p>Rentasunnyplace ofrece a los nuevos hu\u00e9spedes la oportunidad de hacer una reserva sin tener que pagar la fianza habitual. Esto es posible hasta un mes antes de la llegada. En ese momento volveremos a evaluar la situaci\u00f3n juntos.<\/p>\n<p>Con suerte, la flexibilidad sin obligaciones financieras ayudar\u00e1 a nuestros hu\u00e9spedes, tan pronto como la situaci\u00f3n lo permita, a disfrutar de inmediato de toda la belleza en esta hermosa parte del sur de Espa\u00f1a.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>","protected":false},"excerpt":{"rendered":"<p>CAMBIO EN EL REGISTRO DE HU\u00c9SPEDES EN ESPA\u00d1A Diciembre 2024: De acuerdo con el Real Decreto 933\/2021 del 26 de octubre, emitido por el gobierno espa\u00f1ol, y el nuevo sistema de registro que lo acompa\u00f1a, estamos obligados a solicitar informaci\u00f3n adicional a nuestros hu\u00e9spedes. A diferencia de otros proveedores, no pedimos esta informaci\u00f3n el d\u00eda [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":27889,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_et_pb_use_builder":"off","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[229],"tags":[],"class_list":["post-3190","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categorizar"],"acf":[],"_links":{"self":[{"href":"https:\/\/rentasunnyplace.com\/es\/wp-json\/wp\/v2\/posts\/3190","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rentasunnyplace.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rentasunnyplace.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rentasunnyplace.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rentasunnyplace.com\/es\/wp-json\/wp\/v2\/comments?post=3190"}],"version-history":[{"count":0,"href":"https:\/\/rentasunnyplace.com\/es\/wp-json\/wp\/v2\/posts\/3190\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rentasunnyplace.com\/es\/wp-json\/wp\/v2\/media\/27889"}],"wp:attachment":[{"href":"https:\/\/rentasunnyplace.com\/es\/wp-json\/wp\/v2\/media?parent=3190"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rentasunnyplace.com\/es\/wp-json\/wp\/v2\/categories?post=3190"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rentasunnyplace.com\/es\/wp-json\/wp\/v2\/tags?post=3190"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}